{"id":1611,"date":"2016-05-16T21:58:53","date_gmt":"2016-05-16T21:58:53","guid":{"rendered":"http:\/\/hotelmenapace.it\/de\/?p=1611"},"modified":"2020-04-16T19:36:26","modified_gmt":"2020-04-16T19:36:26","slug":"pai-torri-del-benaco","status":"publish","type":"post","link":"https:\/\/hotelmenapace.it\/de\/pai-torri-del-benaco\/","title":{"rendered":"Pai Torri del Benaco"},"content":{"rendered":"<p>Die ersten belegbaren Schriften \u00fcber die Existenz dieses Ortsteils gehen zur\u00fcck bis in das 10. Jahrhundert.<br \/>\nDer antike Ortskern mit seinen guterhaltenen H\u00e4usergruppen liegt am Fu\u00dfe des h\u00fcligen Monte Baldogebirges.<\/p>\n<p>Es war Schutsburg in der Antike, selbige wurde aber w\u00e4hrend einer Schlacht mit Koenig Barbarossa vollkommen zerst\u00f6rt.<br \/>\nPai hat eine sch\u00f6ne Pfarrkirche, die im 17. Jahrhundert erweitert wurde. In dem Kirchenschiff kann man wertvolle Fresken<br \/>\naus dem 13.\/14. Jahrhundert und herrliche \u00d6lgem\u00e4lde aus dem 18. Jahrhundert besichtigen.<\/p>\n<p>Vor vielen Jahren hat sich ein Teil der Bev\u00f6lkerung von Pai unten an der Seek\u00fcste niedergelassen,<br \/>\nsomit wurde der Ortsteil &#8222;Pai di sotto&#8220; gegr\u00fcndet. Hier, in der N\u00e4he des Friedhofes, finden wir die kleine Kirche &#8222;San Gregorio&#8220;<br \/>\naus den 14. Jahrhundert mit wertvollen Fresken aus den 12.\/13. Jahrhundert.<\/p>\n<hr>\n<p>Rif.: Professor Giorgio Vedovelli &#8211; &#8222;Itinerari alle incisioni rupestri di Torri del Benaco e Garda&#8220;<\/p>\n<hr>\n<h3>Galleria<\/h3>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Die ersten belegbaren Schriften \u00fcber die Existenz dieses Ortsteils gehen zur\u00fcck bis in das 10. Jahrhundert. Der antike Ortskern mit seinen guterhaltenen H\u00e4usergruppen liegt am <a href=\"https:\/\/hotelmenapace.it\/de\/pai-torri-del-benaco\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":1610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[31,13,36],"tags":[],"class_list":["post-1611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gardasee-urlaub","category-info-torri","category-wandern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pai Torri del Benaco - Hotel Menapace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pai Torri del Benaco - Hotel Menapace\" \/>\n<meta property=\"og:description\" content=\"Die ersten belegbaren Schriften \u00fcber die Existenz dieses Ortsteils gehen zur\u00fcck bis in das 10. Jahrhundert. Der antike Ortskern mit seinen guterhaltenen H\u00e4usergruppen liegt am [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Menapace\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-16T21:58:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-16T19:36:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotelmenapace.it\/wp-content\/uploads\/pai-di-sopra-pai-di-sotto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/313a67f22008d666ea61dfeb50f45c6c\"},\"headline\":\"Pai Torri del Benaco\",\"datePublished\":\"2016-05-16T21:58:53+00:00\",\"dateModified\":\"2020-04-16T19:36:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/\"},\"wordCount\":153,\"image\":{\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotelmenapace.it\\\/wp-content\\\/uploads\\\/pai-di-sopra-pai-di-sotto.jpg\",\"articleSection\":[\"Gardasee Urlaub\",\"Info Torri\",\"Wandern\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/\",\"url\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/\",\"name\":\"Pai Torri del Benaco - Hotel Menapace\",\"isPartOf\":{\"@id\":\"\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotelmenapace.it\\\/wp-content\\\/uploads\\\/pai-di-sopra-pai-di-sotto.jpg\",\"datePublished\":\"2016-05-16T21:58:53+00:00\",\"dateModified\":\"2020-04-16T19:36:26+00:00\",\"author\":{\"@id\":\"\\\/#\\\/schema\\\/person\\\/313a67f22008d666ea61dfeb50f45c6c\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hotelmenapace.it\\\/pai-di-torri-del-benaco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotelmenapace.it\\\/wp-content\\\/uploads\\\/pai-di-sopra-pai-di-sotto.jpg\",\"contentUrl\":\"https:\\\/\\\/hotelmenapace.it\\\/wp-content\\\/uploads\\\/pai-di-sopra-pai-di-sotto.jpg\",\"width\":960,\"height\":350},{\"@type\":\"WebSite\",\"@id\":\"\\\/#website\",\"url\":\"\\\/\",\"name\":\"Hotel Menapace\",\"description\":\"Pai - Torri del Benaco - Lago di Garda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\\\/#\\\/schema\\\/person\\\/313a67f22008d666ea61dfeb50f45c6c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb16c298ba01be5f6e1bb98bc31fcc39f8c45f589113076c2684f905854dece5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb16c298ba01be5f6e1bb98bc31fcc39f8c45f589113076c2684f905854dece5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb16c298ba01be5f6e1bb98bc31fcc39f8c45f589113076c2684f905854dece5?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/hotelmenapace.it\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pai Torri del Benaco - Hotel Menapace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/","og_locale":"de_DE","og_type":"article","og_title":"Pai Torri del Benaco - Hotel Menapace","og_description":"Die ersten belegbaren Schriften \u00fcber die Existenz dieses Ortsteils gehen zur\u00fcck bis in das 10. Jahrhundert. Der antike Ortskern mit seinen guterhaltenen H\u00e4usergruppen liegt am [...]","og_url":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/","og_site_name":"Hotel Menapace","article_published_time":"2016-05-16T21:58:53+00:00","article_modified_time":"2020-04-16T19:36:26+00:00","og_image":[{"width":960,"height":350,"url":"https:\/\/hotelmenapace.it\/wp-content\/uploads\/pai-di-sopra-pai-di-sotto.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/#article","isPartOf":{"@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/"},"author":{"name":"admin","@id":"\/#\/schema\/person\/313a67f22008d666ea61dfeb50f45c6c"},"headline":"Pai Torri del Benaco","datePublished":"2016-05-16T21:58:53+00:00","dateModified":"2020-04-16T19:36:26+00:00","mainEntityOfPage":{"@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/"},"wordCount":153,"image":{"@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/#primaryimage"},"thumbnailUrl":"https:\/\/hotelmenapace.it\/wp-content\/uploads\/pai-di-sopra-pai-di-sotto.jpg","articleSection":["Gardasee Urlaub","Info Torri","Wandern"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/","url":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/","name":"Pai Torri del Benaco - Hotel Menapace","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/#primaryimage"},"image":{"@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/#primaryimage"},"thumbnailUrl":"https:\/\/hotelmenapace.it\/wp-content\/uploads\/pai-di-sopra-pai-di-sotto.jpg","datePublished":"2016-05-16T21:58:53+00:00","dateModified":"2020-04-16T19:36:26+00:00","author":{"@id":"\/#\/schema\/person\/313a67f22008d666ea61dfeb50f45c6c"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotelmenapace.it\/pai-di-torri-del-benaco\/#primaryimage","url":"https:\/\/hotelmenapace.it\/wp-content\/uploads\/pai-di-sopra-pai-di-sotto.jpg","contentUrl":"https:\/\/hotelmenapace.it\/wp-content\/uploads\/pai-di-sopra-pai-di-sotto.jpg","width":960,"height":350},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Hotel Menapace","description":"Pai - Torri del Benaco - Lago di Garda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"\/#\/schema\/person\/313a67f22008d666ea61dfeb50f45c6c","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bb16c298ba01be5f6e1bb98bc31fcc39f8c45f589113076c2684f905854dece5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb16c298ba01be5f6e1bb98bc31fcc39f8c45f589113076c2684f905854dece5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb16c298ba01be5f6e1bb98bc31fcc39f8c45f589113076c2684f905854dece5?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/hotelmenapace.it\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/posts\/1611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/comments?post=1611"}],"version-history":[{"count":1,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/posts\/1611\/revisions"}],"predecessor-version":[{"id":1612,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/posts\/1611\/revisions\/1612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/media\/1610"}],"wp:attachment":[{"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/media?parent=1611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/categories?post=1611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotelmenapace.it\/de\/wp-json\/wp\/v2\/tags?post=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}